{"id":103560,"date":"2010-04-22T07:36:33","date_gmt":"2010-04-22T06:36:33","guid":{"rendered":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/"},"modified":"2010-04-22T07:36:33","modified_gmt":"2010-04-22T06:36:33","slug":"kartell-nouveautes-2010","status":"publish","type":"post","link":"https:\/\/www.joyana.fr\/ja\/kartell-nouveautes-2010\/103560\/","title":{"rendered":"KARTELL &#8211; Nouveaut\u00e9s 2010"},"content":{"rendered":"<p>Nombres de nos lecteurs sont fans de <strong>Kartell<\/strong>, c&#8217;est donc avec joie que nous vous pr\u00e9sentons en exclusivit\u00e9 les premi\u00e8res images du <strong>catalogue<\/strong> et des<strong> nouveaut\u00e9s 2010<\/strong>&#8230;<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_ghost-buster.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p>Ci-dessus la commode Ghost Buster de Starck, aux lignes plus \u00e9pur\u00e9es, moins baroques, compar\u00e9 au prototype que nous avions vu au Milan Design Week 2009&#8230; Et ci-dessous sa petite soeur la Small Ghost.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_small-ghost-buster.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_masters.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p>La <a title=\"MASTERS STARCK\" href=\"https:\/\/joyana.fr\/3-masters-for-1-masters-x-starck\/\">Masters de Starck &#038; Quitllet<\/a> qui sortira finalement dans une version satin\u00e9e plut\u00f4t que laqu\u00e9e comme pr\u00e9vue au d\u00e9part&#8230; Nous on pr\u00e9f\u00e8re et vous ???<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_plastic-duo.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p>Ci-dessus le canap\u00e9 Plastic Duo qui arborera de nouvelles finitions en <strong>2010<\/strong> !!!<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_bloom.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p>Parmi ces <strong>nouveaut\u00e9s 2010 Kartell<\/strong>, on adore le lustre Bloom de Ferruccio Laviani qui \u00e9clot en une scintillante et somptueuse cascade de fleurs !!! L&#8217;abat-jour est constitu\u00e9 d&#8217;une structure en polycarbonate sur laquelle se clipsent une multitude de d\u00e9licates petites fleurs. Le r\u00e9sultat est une pi\u00e8ce produite industriellement mais avec les formes et la complexit\u00e9 stylistique d&#8217;une pi\u00e8ce artisanale&#8230;<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_image-18.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p>On adore la version rose et noir qui nous ferait presque penser au cerisiers japonais en fleur !!!<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_image-11.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p>Nous finissons avec un autre coup de coeur pour la nouvelle <a title=\"MR  IMPOSSIBLE\" href=\"https:\/\/joyana.fr\/chaise-mr-impossible-par-philippe-starck\/\">Mr  Impossible<\/a>, intitul\u00e9e Super Impossible -qui revient dans une version encore plus chic, les pieds et la coque de la m\u00eame  couleur. Une finition ultra brillante sur l&#8217;assise et la coque, qui  conf\u00e8re \u00e0 Super Impossible une apparence sophistiqu\u00e9e, sensuelle et  percutante&#8230;<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/joyana.fr\/wp-content\/uploads\/kartell_2010_image-16.jpg?ssl=1\" alt=\"KARTELL - Nouveaut\u00e9s 2010\" hspace=\"8\" align=\"top\" \/><\/p>\n<p>Ces <strong>nouveaut\u00e9s Kartell 2010<\/strong> sont ou seront disponibles chez\u00a0 <a href=\"http:\/\/ad.zanox.com\/ppc\/?12733943C479149178T\">MADE IN DESIGN<\/a> et dans tous les Kartell Store.<\/p>\n<p><strong><a title=\"KARTELL\" href=\"http:\/\/www.kartell.it\/\">http:\/\/www.kartell.it\/<\/a><\/strong><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><a title=\"blog design\" href=\"https:\/\/joyana.fr\/\">Jo Yana <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nombres de nos lecteurs sont fans de Kartell, c&#8217;est donc avec joie que nous vous pr\u00e9sentons en exclusivi [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":103561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[938,905,983],"tags":[78,982,9],"class_list":{"0":"post-103560","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualite-deco-design","8":"category-deco-design","9":"category-kartell","10":"tag-design","11":"tag-kartell","12":"tag-starck","13":"entry"},"featured_image_urls":{"full":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,false],"thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=264%2C389&ssl=1",264,389,true],"medium_large":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"large":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"1536x1536":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"2048x2048":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"featured-thumb":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C736&ssl=1",500,736,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C400&ssl=1",500,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C600&ssl=1",500,600,true],"author-pro-image":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=360%2C570&ssl=1",360,570,true],"slider":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C400&ssl=1",500,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=272%2C182&ssl=1",272,182,true]},"post_excerpt_stackable":"<p>Nombres de nos lecteurs sont fans de Kartell, c&#8217;est donc avec joie que nous vous pr\u00e9sentons en&hellip;<\/p>\n","category_list":"<a href=\"https:\/\/www.joyana.fr\/ja\/category\/deco-design\/actualite\/actualite-deco-design\/\" rel=\"category tag\">Actualit\u00e9 D\u00e9co-Design<\/a>, <a href=\"https:\/\/www.joyana.fr\/ja\/category\/deco-design\/\" rel=\"category tag\">DECO-DESIGN<\/a>, <a href=\"https:\/\/www.joyana.fr\/ja\/category\/marques\/kartell\/\" rel=\"category tag\">Kartell<\/a>","author_info":{"display_name":"Jo Yana","author_link":"https:\/\/www.joyana.fr\/ja\/author\/joyana\/"},"comments_num":"14 comments","featured_image_urls_v2":{"full":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,false],"thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=264%2C389&ssl=1",264,389,true],"medium_large":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"large":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"1536x1536":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"2048x2048":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"featured-thumb":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C736&ssl=1",500,736,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C400&ssl=1",500,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C600&ssl=1",500,600,true],"author-pro-image":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=360%2C570&ssl=1",360,570,true],"slider":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C400&ssl=1",500,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=272%2C182&ssl=1",272,182,true]},"post_excerpt_stackable_v2":"<p>Nombres de nos lecteurs sont fans de Kartell, c&#8217;est donc avec joie que nous vous pr\u00e9sentons en&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/www.joyana.fr\/ja\/category\/deco-design\/actualite\/actualite-deco-design\/\" rel=\"category tag\">Actualit\u00e9 D\u00e9co-Design<\/a>, <a href=\"https:\/\/www.joyana.fr\/ja\/category\/deco-design\/\" rel=\"category tag\">DECO-DESIGN<\/a>, <a href=\"https:\/\/www.joyana.fr\/ja\/category\/marques\/kartell\/\" rel=\"category tag\">Kartell<\/a>","author_info_v2":{"name":"Jo Yana","url":"https:\/\/www.joyana.fr\/ja\/author\/joyana\/"},"comments_num_v2":"14 comments","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KARTELL - Nouveaut\u00e9s 2010 - JO YANA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KARTELL - Nouveaut\u00e9s 2010 - JO YANA\" \/>\n<meta property=\"og:description\" content=\"Nombres de nos lecteurs sont fans de Kartell, c&#8217;est donc avec joie que nous vous pr\u00e9sentons en exclusivi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joyana.fr\/ja\/kartell-nouveautes-2010\/103560\/\" \/>\n<meta property=\"og:site_name\" content=\"JO YANA\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-22T06:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"736\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo Yana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Jo_Yana\" \/>\n<meta name=\"twitter:site\" content=\"@Jo_Yana\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo Yana\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/\"},\"author\":{\"name\":\"Jo Yana\",\"@id\":\"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"headline\":\"KARTELL &#8211; Nouveaut\u00e9s 2010\",\"datePublished\":\"2010-04-22T06:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"image\":{\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1\",\"keywords\":[\"DESIGN\",\"Kartell\",\"STARCK\"],\"articleSection\":[\"Actualit\u00e9 D\u00e9co-Design\",\"DECO-DESIGN\",\"Kartell\"],\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/\",\"url\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/\",\"name\":\"KARTELL - Nouveaut\u00e9s 2010 - JO YANA\",\"isPartOf\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1\",\"datePublished\":\"2010-04-22T06:36:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1\",\"width\":500,\"height\":736},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.joyana.fr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KARTELL &#8211; Nouveaut\u00e9s 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joyana.fr\/en\/#website\",\"url\":\"https:\/\/www.joyana.fr\/en\/\",\"name\":\"JO YANA\",\"description\":\"Blog Mode Homme, Lifestyle, D\u00e9co-Design\",\"publisher\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joyana.fr\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c\",\"name\":\"Jo Yana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1\",\"width\":343,\"height\":164,\"caption\":\"Jo Yana\"},\"logo\":{\"@id\":\"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/image\/\"},\"description\":\"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \\\"POUR L'AMOUR DU BEAU\\\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...\",\"sameAs\":[\"https:\/\/joyana.fr\/\"],\"url\":\"https:\/\/www.joyana.fr\/ja\/author\/joyana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KARTELL - Nouveaut\u00e9s 2010 - JO YANA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/","og_locale":"ja_JP","og_type":"article","og_title":"KARTELL - Nouveaut\u00e9s 2010 - JO YANA","og_description":"Nombres de nos lecteurs sont fans de Kartell, c&#8217;est donc avec joie que nous vous pr\u00e9sentons en exclusivi [&hellip;]","og_url":"https:\/\/www.joyana.fr\/ja\/kartell-nouveautes-2010\/103560\/","og_site_name":"JO YANA","article_published_time":"2010-04-22T06:36:33+00:00","og_image":[{"width":500,"height":736,"url":"https:\/\/joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg","type":"image\/jpeg"}],"author":"Jo Yana","twitter_card":"summary_large_image","twitter_creator":"@Jo_Yana","twitter_site":"@Jo_Yana","twitter_misc":{"\u57f7\u7b46\u8005":"Jo Yana","\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#article","isPartOf":{"@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/"},"author":{"name":"Jo Yana","@id":"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"headline":"KARTELL &#8211; Nouveaut\u00e9s 2010","datePublished":"2010-04-22T06:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"image":{"@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1","keywords":["DESIGN","Kartell","STARCK"],"articleSection":["Actualit\u00e9 D\u00e9co-Design","DECO-DESIGN","Kartell"],"inLanguage":"ja","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/","url":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/","name":"KARTELL - Nouveaut\u00e9s 2010 - JO YANA","isPartOf":{"@id":"https:\/\/www.joyana.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage"},"image":{"@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1","datePublished":"2010-04-22T06:36:33+00:00","breadcrumb":{"@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#primaryimage","url":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1","width":500,"height":736},{"@type":"BreadcrumbList","@id":"https:\/\/joyana.fr\/kartell-nouveautes-2010\/103560\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joyana.fr\/en\/"},{"@type":"ListItem","position":2,"name":"KARTELL &#8211; Nouveaut\u00e9s 2010"}]},{"@type":"WebSite","@id":"https:\/\/www.joyana.fr\/en\/#website","url":"https:\/\/www.joyana.fr\/en\/","name":"JO YANA","description":"Blog Mode Homme, Lifestyle, D\u00e9co-Design","publisher":{"@id":"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joyana.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":["Person","Organization"],"@id":"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/cf2a1ad12a27c12c21801075bf37407c","name":"Jo Yana","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/image\/","url":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/2016\/08\/cropped-joyana-logo-black-360x180.png?fit=343%2C164&ssl=1","width":343,"height":164,"caption":"Jo Yana"},"logo":{"@id":"https:\/\/www.joyana.fr\/en\/#\/schema\/person\/image\/"},"description":"Jo Yana est le cr\u00e9ateur et r\u00e9dacteur en chef des sites DECO-DESIGN. Passionn\u00e9 de Design, Mode, Photo, Luxe, Lifestyle, Musique, mais avant tout Blogueur ! Le plaisir de partager l'anime et a comme devise \"POUR L'AMOUR DU BEAU\". Retrouvez le aussi sur son blog personnel - https:\/\/joyana.fr...","sameAs":["https:\/\/joyana.fr\/"],"url":"https:\/\/www.joyana.fr\/ja\/author\/joyana\/"}]}},"author_meta":{"display_name":"Jo Yana","author_link":"https:\/\/www.joyana.fr\/ja\/author\/joyana\/"},"featured_img":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=264%2C389&ssl=1","featured_image_src":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C400&ssl=1","featured_image_src_square":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C600&ssl=1","jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,false],"thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=264%2C389&ssl=1",264,389,true],"medium_large":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"large":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"1536x1536":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"2048x2048":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"featured-thumb":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C736&ssl=1",500,736,true],"ab-block-post-grid-landscape":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C400&ssl=1",500,400,true],"ab-block-post-grid-square":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C600&ssl=1",500,600,true],"author-pro-image":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=360%2C570&ssl=1",360,570,true],"slider":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=500%2C400&ssl=1",500,400,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=450%2C450&ssl=1",450,450,true],"woocommerce_single":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?fit=500%2C736&ssl=1",500,736,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=180%2C180&ssl=1",180,180,true],"sow-carousel-default":["https:\/\/i0.wp.com\/www.joyana.fr\/wp-content\/uploads\/old\/kartell_2010_ghost-buster.jpg?resize=272%2C182&ssl=1",272,182,true]},"uagb_author_info":{"display_name":"Jo Yana","author_link":"https:\/\/www.joyana.fr\/ja\/author\/joyana\/"},"uagb_comment_info":14,"uagb_excerpt":"Nombres de nos lecteurs sont fans de Kartell, c&#8217;e&hellip;","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.joyana.fr\/ja\/category\/deco-design\/actualite\/actualite-deco-design\/\" class=\"advgb-post-tax-term\">Actualit\u00e9 D\u00e9co-Design<\/a>","<a href=\"https:\/\/www.joyana.fr\/ja\/category\/deco-design\/\" class=\"advgb-post-tax-term\">DECO-DESIGN<\/a>","<a href=\"https:\/\/www.joyana.fr\/ja\/category\/marques\/kartell\/\" class=\"advgb-post-tax-term\">Kartell<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Actualit\u00e9 D\u00e9co-Design<\/span>","<span class=\"advgb-post-tax-term\">DECO-DESIGN<\/span>","<span class=\"advgb-post-tax-term\">Kartell<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.joyana.fr\/ja\/category\/marques\/kartell\/\" class=\"advgb-post-tax-term\">DESIGN<\/a>","<a href=\"https:\/\/www.joyana.fr\/ja\/category\/marques\/kartell\/\" class=\"advgb-post-tax-term\">Kartell<\/a>","<a href=\"https:\/\/www.joyana.fr\/ja\/category\/marques\/kartell\/\" class=\"advgb-post-tax-term\">STARCK<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">DESIGN<\/span>","<span class=\"advgb-post-tax-term\">Kartell<\/span>","<span class=\"advgb-post-tax-term\">STARCK<\/span>"]}},"comment_count":14,"relative_dates":{"created":"Posted 16\u5e74 ago","modified":"Updated 16\u5e74 ago"},"absolute_dates":{"created":"Posted on 22 4\u6708 2010","modified":"Updated on 22 4\u6708 2010"},"absolute_dates_time":{"created":"Posted on 22 4\u6708 2010 7:36","modified":"Updated on 22 4\u6708 2010 7:36"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bteI-qWk","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/posts\/103560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/comments?post=103560"}],"version-history":[{"count":0,"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/posts\/103560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/media\/103561"}],"wp:attachment":[{"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/media?parent=103560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/categories?post=103560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joyana.fr\/ja\/wp-json\/wp\/v2\/tags?post=103560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}